{"id":22350,"date":"2024-08-07T14:13:38","date_gmt":"2024-08-07T17:13:38","guid":{"rendered":"https:\/\/www.agroeducacion.com\/website\/?p=22350"},"modified":"2024-08-07T14:13:39","modified_gmt":"2024-08-07T17:13:39","slug":"los-eventos-bursatiles-invitan-a-bajar-riesgo-precios","status":"publish","type":"post","link":"https:\/\/www.agroeducacion.com\/website\/los-eventos-bursatiles-invitan-a-bajar-riesgo-precios\/","title":{"rendered":"Los Eventos Burs\u00e1tiles Invitan a Bajar Riesgo Precios"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"256\" src=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/Sin-titulo-48-1024x256.jpeg\" alt=\"\" class=\"wp-image-22353\" srcset=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/Sin-titulo-48-1024x256.jpeg 1024w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/Sin-titulo-48-300x75.jpeg 300w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/Sin-titulo-48-768x192.jpeg 768w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/Sin-titulo-48.jpeg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Por\u00a0<em>Marianela De Emilio<\/em>\u00a0|\u00a0<em>Ing. Agr. Msc. Agronegocios<\/em>\u00a0<em>\u2013 INTA<\/em>\u00a0CIEP<\/strong><\/p>\n\n\n\n<p>La semana inici\u00f3 con eventos burs\u00e1tiles que dieron mucho que hablar, al punto de referenciarlos con el famoso lunes negro de 1987, en el que una suba de tasas en Estados Unidos impactaba a la baja en las principales bolsas del mundo en dimensiones nunca antes vistas. En esta oportunidad fue Jap\u00f3n qui\u00e9n subi\u00f3 su tasa de inter\u00e9s, mientras Estados Unidos debate respecto a bajar la suya, causando una catarata de eventos a nivel global, que a\u00fan siguen suscit\u00e1ndose, y en cuyo camino el mercado de granos queda expuesto a riesgo de bajas. Ver que pas\u00f3 y que puede pasar para tomar decisiones en torno al riesgo precio.<\/p>\n\n\n\n<p>Jap\u00f3n, luego de muchos a\u00f1os de tasas de inter\u00e9s negativas o cero, toma la decisi\u00f3n de subir su tasa de pol\u00edtica monetaria a 0,25% anual, lo que cambia las reglas de juego en el mercado financiero global. Como se observa en el primer gr\u00e1fico, el Yen Japon\u00e9s reacciona elevando su valor comparado con el D\u00f3lar u otras monedas fuertes. Esta suba de tasas encarece toda deuda tomada sobre Jap\u00f3n, y gener\u00f3 un cierre masivo de posiciones de deuda abiertas sobre ese pa\u00eds, causando el desplome del \u00edndice Nikkei 225, que representa la Bolsa de valores de Jap\u00f3n. Al mismo tiempo, Estados Unidos, que hace meses sostiene una tasa de inter\u00e9s elevada, como se desarroll\u00f3 en el informe p\u00fablico de la semana pasada, se debate desde la Reserva Federal de ese pa\u00eds sobre una baja de tasas, ante indicios de recesi\u00f3n econ\u00f3mica como el aumento del desempleo. Si bien Estados Unidos a\u00fan no ha puesto fecha cierta a dicha baja de tasas, el D\u00f3lar estadounidense se debilita por mayor probabilidad de que esto ocurra, como se observa en el gr\u00e1fico. Por tanto, suba de tasas de Jap\u00f3n, pa\u00eds que cumple un fuerte rol de acreedor para inversionistas internacionales, sumado a potenciales bajas de tasas de Estados Unidos, pa\u00eds destino de muchas inversiones globales, causa el escape de inversiones de este \u00faltimo y el cierre de posiciones de deuda de Jap\u00f3n, como puntapi\u00e9 inicial de disminuir exposici\u00f3n al riesgo de p\u00e9rdida de capitales por quedar endeudados a tasas altas en Jap\u00f3n e invertidos a bajas tasas en Estados Unidos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"413\" src=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto1-1024x413.jpeg\" alt=\"\" class=\"wp-image-22351\" srcset=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto1-1024x413.jpeg 1024w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto1-300x121.jpeg 300w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto1-768x310.jpeg 768w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto1-1536x620.jpeg 1536w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto1-2048x827.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Por \u00faltimo, para completar el cuadro de situaci\u00f3n, se observa la fuerte suba del \u00cdndice VIX, conocido como \u00edndice del miedo, por representar la probabilidad de aumento en volatilidad del \u00edndice SyP500, uno de los \u00edndices que representa el movimiento de fuertes empresas que cotizan en Bolsa en Chicago. Esta suba del VIX representa el temor de capitales del mundo, que empiezan a buscar refugio en activos de menor riesgo, para bajar su exposici\u00f3n al riesgo de p\u00e9rdidas, esto caus\u00f3 las fuertes bajas observadas en muchas bolsas internacionales.<\/p>\n\n\n\n<p>Cuando vamos al mercado de granos en particular, la reacci\u00f3n inmediata fue lateral alcista, dadas las bajas en el D\u00f3lar estadounidense, que traen mayor poder de compra a pa\u00edses que se proveen de sus exportaciones, lo que eleva la demanda y da margen para suba de precios de los granos. No obstante, esa solo fue una reacci\u00f3n de corto plazo, ya que, ante la expectativa de un mundo que muestra m\u00e1s signos de recesi\u00f3n que de reactivaci\u00f3n, a lo que se suma la tendencia de grandes capitales de disminuir posiciones que consideran riesgosas, como es el caso del mercado de granos, la demanda global de los commodities tiende a debilitarse en el mediano plazo, lo que resulta en baja de precios internacionales, como puede verse en el camino m\u00e1s frecuente del precio de soja, ma\u00edz y trigo durante los \u00faltimos meses en el mercado de Chicago.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"153\" src=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto2-1024x153.jpeg\" alt=\"\" class=\"wp-image-22352\" style=\"width:839px;height:auto\" srcset=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto2-1024x153.jpeg 1024w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto2-300x45.jpeg 300w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto2-768x115.jpeg 768w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto2-1536x230.jpeg 1536w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2024\/08\/foto2-2048x307.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Es importante destacar que la campa\u00f1a 24\/25 sigue evolucionando en \u00f3ptimas condiciones en el Hemisferio Norte, principalmente soja y ma\u00edz en Estados Unidos, con 68% y 67% de la soja y el ma\u00edz en condiciones buenas a excelentes respectivamente, versus 54% y 57% en esa condici\u00f3n el a\u00f1o pasado a igual fecha. Adem\u00e1s, hay alto porcentaje de superficie de soja y ma\u00edz en estados avanzados de reproducci\u00f3n en USA, que no han atravesado importantes complicaciones clim\u00e1ticas, lo que hace proyectar excelentes rendimientos para este a\u00f1o, proyecciones que ser\u00e1n ratificadas o rectificadas este viernes 9 de agosto desde el informe de Oferta y Demanda mundial del USDA. Si el informe del USDA afianza la idea de mayor producci\u00f3n de soja y ma\u00edz 24\/25 tanto para Estados Unidos como para el mundo, los precios de los granos seguir\u00e1n presionados a la baja.<\/p>\n\n\n\n<p>En cuanto a los capitales que apuestan en el mercado de granos, es importante tener en cuenta que la recomendaci\u00f3n m\u00e1s frecuente en este contexto es bajar el nivel de exposici\u00f3n al riesgo, lo que los aleja de apostar en estos mercados. Antes de salir de estos mercados, deben desarmar posiciones, y, conociendo el gran volumen de capital que apuesta a la baja, principalmente en ma\u00edz y en soja, es posible que se cierren posiciones vendidas, es decir, salgan de ventas comprando, lo que traer\u00eda en el corto plazo movimiento alcista de precios, que podr\u00edan ser aprovechados por los vendedores de granos para salir a la venta y capturar mejores precios en el corto plazo.<\/p>\n\n\n\n<p>La recomendaci\u00f3n que debieran considerar los productores de granos, que a\u00fan deben poner precio a 31% del trigo, 58% del ma\u00edz y 66% de la soja, es la misma que se est\u00e1 dando a los grandes inversionistas del mundo, bajar la exposici\u00f3n al riesgo, en el caso de los granos significa bajar la proporci\u00f3n de cosecha 23\/24 sin precio, as\u00ed como aprovechar toda suba de la futura 24\/25 para cubrir valores que superen los futuros actuales.<\/p>\n\n\n\n<p><strong>Conclusiones:<\/strong>&nbsp;El mundo est\u00e1 en un camino que aumenta la incertidumbre respecto a las principales econom\u00edas del mundo, no solo por subas y bajas de tasas de inter\u00e9s, sino por conflictos geopol\u00edticos que no han terminado. La producci\u00f3n de granos no muestra fuertes amenazas clim\u00e1ticas en el mediano plazo para Estados Unidos ni Sudam\u00e9rica, lo que trae calma a la demanda internacional. La idea de recesi\u00f3n global detiene el deseo de exposici\u00f3n al riesgo, conduciendo capitales a destinos m\u00e1s seguros, como oro, bonos de largo plazo, etc., y quitando capitales a mercados m\u00e1s arriesgados, como mercados de desarrollo tecnol\u00f3gico y tambi\u00e9n el mercado de agro alimentos. La expectativa es bajista, por lo que la exposici\u00f3n al riesgo de bajas para el productor agr\u00edcola debe ser reducida.<\/p>\n\n\n\n<p><strong>Por\u00a0<em>Marianela De Emilio<\/em>\u00a0|\u00a0<em>Ing. Agr. Msc. Agronegocios<\/em>\u00a0<em>\u2013 INTA<\/em>\u00a0CIEP<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por\u00a0Marianela De Emilio\u00a0|\u00a0Ing. Agr. Msc. Agronegocios\u00a0\u2013 INTA\u00a0CIEP La semana inici\u00f3 con eventos burs\u00e1tiles que dieron mucho que hablar, al punto de referenciarlos con el famoso lunes negro de 1987, en el que una suba de tasas en Estados Unidos impactaba a la baja en las principales bolsas del mundo en dimensiones nunca antes vistas. En &hellip;<\/p>\n","protected":false},"author":207,"featured_media":22354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,51,87],"tags":[],"class_list":["post-22350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-granos","category-novedades"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts\/22350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/users\/207"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/comments?post=22350"}],"version-history":[{"count":1,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts\/22350\/revisions"}],"predecessor-version":[{"id":22355,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts\/22350\/revisions\/22355"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/media\/22354"}],"wp:attachment":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/media?parent=22350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/categories?post=22350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/tags?post=22350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}