{"id":19402,"date":"2023-06-12T08:25:38","date_gmt":"2023-06-12T11:25:38","guid":{"rendered":"https:\/\/www.agroeducacion.com\/website\/?p=19402"},"modified":"2023-06-12T08:52:33","modified_gmt":"2023-06-12T11:52:33","slug":"on-off-el-mercado-de-granos-esta-apagado","status":"publish","type":"post","link":"https:\/\/www.agroeducacion.com\/website\/on-off-el-mercado-de-granos-esta-apagado\/","title":{"rendered":"ON-OFF &#8211; El mercado de granos est\u00e1 apagado"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"427\" src=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2023\/06\/Mesa-de-trabajo-1-1-1024x427.png\" alt=\"\" class=\"wp-image-19403\" srcset=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2023\/06\/Mesa-de-trabajo-1-1-1024x427.png 1024w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2023\/06\/Mesa-de-trabajo-1-1-300x125.png 300w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2023\/06\/Mesa-de-trabajo-1-1-768x320.png 768w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2023\/06\/Mesa-de-trabajo-1-1-1536x640.png 1536w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2023\/06\/Mesa-de-trabajo-1-1.png 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><strong>Por Eduardo Lombardo &#8211; Director de Aipsa+<\/strong><\/p>\n\n\n\n<p>Mientras que a nivel internacional los eventos que inciden sobre el mercado de granos siguen su curso, aqu\u00ed en el mercado argentino, la actividad est\u00e1 en los niveles m\u00e1s bajos de los \u00faltimos tiempos. Solo un dato muestra la profundidad de esta afirmaci\u00f3n: la cantidad de camiones que arribaron a los puertos del up river en uno de los d\u00edas de la semana que acaba de finalizar es la m\u00e1s baja que se registra en los \u00faltimos 22 a\u00f1os, seg\u00fan informaci\u00f3n de la bolsa de Comercio de Rosario.<\/p>\n\n\n\n<p>Los factores bajistas y alcistas que ocurren y se desarrollan en distintas partes del planeta, no logran despegar al mercado local de la inacci\u00f3n en la que est\u00e1 inmerso. La guerra en Ucrania, el \u00faltimo informe del Usda, el aumento de la demanda de aceites, las altas tasas de inter\u00e9s en el pa\u00eds del norte, el rumor sobre la decisi\u00f3n de la OPEP de reducir la producci\u00f3n de petr\u00f3leo, no generan efectos determinantes que puedan provocar una influencia mayor que las cuestiones relacionadas a la peor sequ\u00eda de los \u00faltimos a\u00f1os, acompa\u00f1ada de un a\u00f1o electoral con una incertidumbre tal, que ha paralizado las decisiones de uno de los principales actores del mercado: el productor agropecuario.<\/p>\n\n\n\n<p>No obstante, estar informados es necesario para estar preparados.&nbsp;<\/p>\n\n\n\n<p>Uno de los factores determinantes en la Guerra, que el \u00faltimo viernes cumpli\u00f3 471 d\u00edas desde su inicio, ocurri\u00f3 esta semana y es por eso que en la zona se sufren las consecuencias de la destrucci\u00f3n de la presa de Jakovka .<\/p>\n\n\n\n<p>El presidente ucraniano, Volod\u00edmir Zelenski, se reuni\u00f3 la noche del jueves y de forma remota con la activista sueca Greta Thunberg y otros expertos y abogados de la causa clim\u00e1tica para evaluar las consecuencias de la destrucci\u00f3n de la presa de Nova Jakovka y buscar f\u00f3rmulas para evitar que la cat\u00e1strofe se repita.<\/p>\n\n\n\n<p>Seg\u00fan el presidente de la oficina presidencial ucraniana, Andriy Yermak, Thunberg expres\u00f3 sus simpat\u00edas a los ucranianos ante el desastre medioambiental que supone la destrucci\u00f3n de la presa del sur de Ucrania y la central hidroel\u00e9ctrica de la que formaba parte esta infraestructura.<\/p>\n\n\n\n<p>Un \u00faltimo informe de la Inteligencia militar brit\u00e1nica sobre el conflicto menciona que Rusia bloquea el funcionamiento del acuerdo que permit\u00eda exportar cereales por el mar Negro. Las inspecciones de barcos se demoran m\u00e1s de los necesario y solo uno o dos son revisados por d\u00eda, comparados con 6-8 en el oto\u00f1o (HN) de 2022. El acuerdo debe renovarse el 16 de julio, y es probable que hasta esa fecha Rusia contin\u00fae entorpeci\u00e9ndolo.&nbsp;<\/p>\n\n\n\n<p>Rusia intenta forzar concesiones para la reapertura del transporte de amonio (usado para fertilizantes) desde Rusia, a trav\u00e9s de Ucrania, para ser exportado por el puerto de Odesa. La tuber\u00eda, que discurre entre Toliatti (en Rusia) y Odesa, ha sido bombardeada en los \u00faltimos d\u00edas.<\/p>\n\n\n\n<p>Esta semana el petr\u00f3leo y el cobre tiraron para arriba las materias primas agr\u00edcolas, pero la tendencia alcista no se mantuvo firme.<\/p>\n\n\n\n<p>El clima en el pa\u00eds del norte tambi\u00e9n genera expectativas y la muy buena producci\u00f3n de ma\u00edz a nivel mundial acompa\u00f1a el ultimo informe del USDA en una tibia baja de precios.<\/p>\n\n\n\n<p>El informe del USDA result\u00f3 a priori de caracter\u00edsticas bajistas para la soja y el ma\u00edz y con se\u00f1ales mixtas para el trigo. En Chicago la soja aumenta, el ma\u00edz disminuye y el trigo opera mixto. Los stocks finales de soja y ma\u00edz, tanto para EE.UU. como a nivel mundial, resultaron superiores a lo que se esperaba. En el caso del trigo, los stocks finales de la 23\/24 estuvieron por debajo de las expectativas en EE.UU., respaldando los precios, pero por encima en el escenario mundial, inform\u00f3 la Bolsa de Comercio de Rosario.<\/p>\n\n\n\n<p>A nivel local la siembra de trigo se activ\u00f3 despu\u00e9s de las lluvias del \u00faltimo fin de semana largo y si bien el retraso respecto a la cantidad de hect\u00e1reas sembradas respecto al a\u00f1o pasado es importante, en especial en el sur bonaerense, ya se logr\u00f3 casi el 20% del \u00e1rea total proyectada. Hablando de proyecciones el volumen estimado para la cosecha supera los 20 millones de toneladas. Nuestras sugerencias y las de nuestros colegas tendientes a la cobertura de precios a cosecha no son, todav\u00eda, tomadas en cuenta<\/p>\n\n\n\n<p>Respecto a la soja los exportadores locales liquidaron 5 mil millones de d\u00f3lares aprovechando el tipo de cambio diferencial del \u201cd\u00f3lar soja III\u201d, pero no lograron comprar toda esa cantidad, todav\u00eda les faltan cerca de 2,2 millones de toneladas. Otra de las muestras de la falta de \u00f3rdenes de venta por parte de los agricultores, que todav\u00eda retienen m\u00e1s de 10Mt<\/p>\n\n\n\n<p>Para el USDA, la producci\u00f3n de ma\u00edz en Argentina se estim\u00f3 en 35,0 Mt, por debajo de lo que esperaban los analistas, mientras que la Bolsa de Cereales de Buenos Aires lo sigue estimando en 36Mt, con un porcentaje de recolecci\u00f3n del 32,6% del \u00e1rea apta en todo el pa\u00eds.<\/p>\n\n\n\n<p>Para refrendar el t\u00edtulo de \u00e9ste art\u00edculo, la Bolsa de Comercio de Rosario en el comentario diario del Mercado F\u00edsico de Granos de \u00e9ste \u00faltimo viernes dice: \u201cJornada de d\u00eda viernes con un menor dinamismo comercial.\u201d, y menciona en su contenido que la Soja tuvo un \u201cdiscreto\u201d dinamismo, en trigo un solo comprador, en ma\u00edz \u201cuna ca\u00edda en el n\u00famero de participantes y un recorte en el abanico de posiciones de compra\u201d, mientras que para girasol, sorgo y cebada \u201cno se dieron ofertas abiertas de compra\u201d<\/p>\n\n\n\n<p>El Mercado de Granos est\u00e1 apagado.<\/p>\n\n\n\n<p>La Bolsa de Cereales de Buenos Aires difundi\u00f3 esta semana un interesante informe sobre la incidencia comparada, de las mal llamadas retenciones (derechos de exportaci\u00f3n) y la diferencia en el tipo de cambio; en los costos de la actividad agr\u00edcola.<\/p>\n\n\n\n<p>Estos aspectos negativos para la actividad y las cuestiones relacionadas con las elecciones, probables listas, alianzas, f\u00f3rmulas electorales, rumores sobre las acciones que oficialistas y opositores podr\u00edan llegar a instrumentar de salir victoriosos, m\u00e1s una gran cantidad de medios period\u00edsticos dedicados al tema, combinados con una, cada vez mayor actividad en las redes sociales, tienen sumergida a una gran parte de la poblaci\u00f3n y entre ellos a nuestros productores, en un mar de dudas e incertidumbres que solo logran paralizar su accionar, al menos en lo relacionado a sus movimientos comerciales y financieros.<\/p>\n\n\n\n<p><strong>Por Eduardo Lombardo &#8211; Director de Aipsa+<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.agroeducacion.com\/postgrado\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"114\" src=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2022\/02\/OPTIMIZADO-ZOCALO-postgrado-2022-1024x114.jpg\" alt=\"\" class=\"wp-image-14433\" srcset=\"https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2022\/02\/OPTIMIZADO-ZOCALO-postgrado-2022-1024x114.jpg 1024w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2022\/02\/OPTIMIZADO-ZOCALO-postgrado-2022-300x33.jpg 300w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2022\/02\/OPTIMIZADO-ZOCALO-postgrado-2022-768x85.jpg 768w, https:\/\/www.agroeducacion.com\/website\/wp-content\/uploads\/2022\/02\/OPTIMIZADO-ZOCALO-postgrado-2022.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p style=\"font-size:12px\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Eduardo Lombardo &#8211; Director de Aipsa+ Mientras que a nivel internacional los eventos que inciden sobre el mercado de granos siguen su curso, aqu\u00ed en el mercado argentino, la actividad est\u00e1 en los niveles m\u00e1s bajos de los \u00faltimos tiempos. Solo un dato muestra la profundidad de esta afirmaci\u00f3n: la cantidad de camiones que &hellip;<\/p>\n","protected":false},"author":207,"featured_media":19403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[81,51,87],"tags":[],"class_list":["post-19402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacados","category-granos","category-novedades"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts\/19402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/users\/207"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/comments?post=19402"}],"version-history":[{"count":6,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts\/19402\/revisions"}],"predecessor-version":[{"id":19412,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/posts\/19402\/revisions\/19412"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/media\/19403"}],"wp:attachment":[{"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/media?parent=19402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/categories?post=19402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.agroeducacion.com\/website\/wp-json\/wp\/v2\/tags?post=19402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}